{"id":527,"date":"2024-12-03T17:43:21","date_gmt":"2024-12-03T17:43:21","guid":{"rendered":"https:\/\/mediapay.site\/?p=527"},"modified":"2024-12-03T17:43:21","modified_gmt":"2024-12-03T17:43:21","slug":"el-consejo-general-de-educacion-de-entre-rios-lanzo-reli-la-solucion-virtual-para-errores-en-liquidaciones-docentes","status":"publish","type":"post","link":"https:\/\/indignados.site\/index.php\/2024\/12\/03\/el-consejo-general-de-educacion-de-entre-rios-lanzo-reli-la-solucion-virtual-para-errores-en-liquidaciones-docentes\/","title":{"rendered":"El Consejo General de Educaci\u00f3n de Entre R\u00edos lanz\u00f3 RELI: la soluci\u00f3n virtual para errores en liquidaciones docentes"},"content":{"rendered":"\n<p>El Consejo General de Educaci\u00f3n (CGE) ha dado un paso importante hacia la modernizaci\u00f3n con la implementaci\u00f3n del Sistema de Reclamo por Errores en Liquidaciones (RELI), una herramienta virtual dise\u00f1ada para que los docentes gestionen r\u00e1pidamente cualquier irregularidad detectada en sus recibos de haberes.<\/p>\n\n\n\n<p>Aprobado el 1 de noviembre mediante la resoluci\u00f3n N\u00ba 3221\/24, este sistema permite realizar reclamos a trav\u00e9s del Sistema de Administraci\u00f3n de la Gesti\u00f3n Educativa (SAGE) y asegura una respuesta en un plazo m\u00e1ximo de cinco d\u00edas h\u00e1biles. Seg\u00fan lo estipulado, si el reclamo es v\u00e1lido, el error ser\u00e1 corregido y se proceder\u00e1 a liquidar la suma faltante, indicando una fecha estimada de pago. En caso de que la liquidaci\u00f3n sea correcta, se brindar\u00e1 una explicaci\u00f3n detallada al reclamante.<\/p>\n\n\n\n<p>Con RELI, se busca evitar largos procesos legales y ofrecer una soluci\u00f3n \u00e1gil, transparente y accesible para los docentes, marcando un avance significativo en la gesti\u00f3n educativa de la provincia.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Consejo General de Educaci\u00f3n (CGE) ha dado un paso importante hacia la modernizaci\u00f3n con la implementaci\u00f3n del Sistema de Reclamo por Errores en Liquidaciones (RELI), una herramienta virtual dise\u00f1ada para que los docentes gestionen r\u00e1pidamente cualquier irregularidad detectada en sus recibos de haberes. Aprobado el 1 de noviembre mediante la resoluci\u00f3n N\u00ba 3221\/24, este [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":528,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[179],"tags":[224,225,226,188,227,228],"class_list":["post-527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-cge","tag-docentes","tag-educacion-2","tag-entre-rios","tag-liquidaciones","tag-reli"],"_links":{"self":[{"href":"https:\/\/indignados.site\/index.php\/wp-json\/wp\/v2\/posts\/527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/indignados.site\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/indignados.site\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/indignados.site\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/indignados.site\/index.php\/wp-json\/wp\/v2\/comments?post=527"}],"version-history":[{"count":0,"href":"https:\/\/indignados.site\/index.php\/wp-json\/wp\/v2\/posts\/527\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/indignados.site\/index.php\/wp-json\/wp\/v2\/media\/528"}],"wp:attachment":[{"href":"https:\/\/indignados.site\/index.php\/wp-json\/wp\/v2\/media?parent=527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/indignados.site\/index.php\/wp-json\/wp\/v2\/categories?post=527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/indignados.site\/index.php\/wp-json\/wp\/v2\/tags?post=527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}